{"id":18596,"date":"2019-10-14T14:05:35","date_gmt":"2019-10-14T19:05:35","guid":{"rendered":"https:\/\/www.erbessd-instruments.com\/docs\/phantom\/sensores-phantom\/phantom-de-corriente"},"modified":"2021-07-22T17:24:20","modified_gmt":"2021-07-22T22:24:20","slug":"phantom-de-corriente","status":"publish","type":"docs","link":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/","title":{"rendered":"Phantom de Corriente"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18596\" class=\"elementor elementor-18596 elementor-18561\" data-elementor-post-type=\"docs\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-22953441 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22953441\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c949bfb\" data-id=\"4c949bfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56c3fd42 elementor-widget elementor-widget-text-editor\" data-id=\"56c3fd42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El sensor Phantom de corriente est\u00e1 dise\u00f1ado para llevar un registro del amperaje de todas las lines electrical que necesites monitorear. Su sencilla forma de sujetar a cualquier superficie te ayudar\u00e1 a monitorear hasta 3 l\u00edneas diferentes por cada sensor de amperaje, con rangos que pueden ir desde los 50 a los 500 amperes. Con esto, el sensor Phantom de corriente es el mejor sensor de Amperaje del mercado.<\/p><p>En este tutorial te mostraremos c\u00f3mo instalar y configurar estos sensores tanto f\u00edsicamente como en el Software Digivibe. Si lo que buscas es un proceso m\u00e1s a detalle, por favor, visita el manual <a href=\"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/phantom-wizard\">Phantom Wizard<\/a><\/p><h2>Los Clamps<\/h2><p><span data-preserver-spaces=\"true\">El componente principal del sensor son los Clamps:<\/span><\/p><ul><li>Entrada nominal: 50\/100\/250\/500 amp<\/li><li>Entrada m\u00e1xima: 100% continuo \/ 150% durante 1 minuto<\/li><li>Impedancia de salida: 7 k\ud835\udec0<\/li><li>Precisi\u00f3n: \u00b1 2%<\/li><li>Dimensiones: 50 cm x 26 cm.<\/li><\/ul><p>Estos Clamps se pueden conectar al sensor Phantom utilizando un cable conector con una entrada LEMO de un lado y zapatas de contacto en el otro. Simplemente conecte el conector a la parte inferior de la abrazadera.<br \/><br \/>Para unir correctamente los Clamps alrededor de una l\u00ednea hay algunas caracter\u00edsticas que debemos tener en cuenta. Una de ellas es que solo pueden leer una l\u00ednea a la vez, esto significa que los Clamps no funcionar\u00e1 en cables empaquetados. Instalarlos de esta manera har\u00e1 que nuestras mediciones sean inexactas. Incluso cuando solo podemos ver un solo cable, dentro de la cubierta varias otras l\u00edneas interferir\u00e1n con el sensor.<\/p><h2>Configuraci\u00f3n en Digivibe<\/h2><div class=\"page\" title=\"Page 24\"><div class=\"layoutArea\"><div class=\"column\">Ve a la ventana phantom y selecciona <strong>asistente. <\/strong>Aparece la ventana del asistente e configuraci\u00f3n phantom, selecciona <strong>siguiente. <\/strong>A continuaci\u00f3n, tenemos dos opciones para agregar nuestros dispositivos phantom: La opci\u00f3n<span style=\"color: #00ff00;\">\u00a0<\/span><span style=\"color: #00ff00;\">A<\/span> nos permite agregar manualmente el c\u00f3digo de nuestro phantom. Con la opci\u00f3n <strong><span style=\"color: #0000ff;\">B <\/span><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">podemos escanear el c\u00f3digo QR del sensor.\u00a0<\/span><\/span><div class=\"page\" title=\"Page 24\"><div class=\"layoutArea\"><div class=\"column\"><h2>A\u00f1adir Phantom<\/h2><h3>A\u00f1adir phantom manualmente<\/h3><p>Es posible a\u00f1adir un dispositivo phantom ingresando el c\u00f3digo del sensor. Selecciona el\u00a0 bot\u00f3n <strong>manualmente. <\/strong>La ventana de c\u00f3digo se abrir\u00e1, introduce el c\u00f3digo phantom 11-ID phantom de la etiqueta QR del sensor (c\u00f3digo de 2-d\u00edgitos del modelo del sensor + n\u00famero de serie de 9-d\u00edgitos del sensor) y selecciona <strong>Ok<\/strong>.\u00a0 El sensor aparecer\u00e1 en la secci\u00f3n de phantom&#8217;s a\u00f1adidos.<\/p><\/div><div class=\"layoutArea\"><div class=\"column\"><h3>A\u00f1adir sensores escaneando el c\u00f3digo QR<\/h3><p>(<strong>Requiere una c\u00e1mara de tablet, laptop o PC<\/strong>): Selecciona el bot\u00f3n<strong> escanear c\u00f3digo. <\/strong>Elige la c\u00e1mara de la lista, posiciona la etiqueta Q enfrente de la c\u00e1mara- ubicarla de manera centrada ycerca para que sea f\u00e1cil de leer. El c\u00f3digo ser\u00e1 capturado autom\u00e1ticamente y se cerrar\u00e1 la ventana de escaneo. El phantom se habr\u00e1 a\u00f1adido.<\/p><\/div><\/div><\/div><\/div><h2>Configurar y nombrar<\/h2><p>La ventana de configurar phantom nos permite organizar nuestros sensores para facilitar su identificaci\u00f3n.\u00a0 Podemos organizar nuestros dispositivos con las siguientes herramientas:<\/p><\/div><\/div><\/div><ul><li>En <strong>grupo<\/strong> podemos agregar al phantom a un grupo previamente creado o crear un nuevo grupo.<\/li><li>En <strong>nombre<\/strong> podemos nombrar a nuestro dispositivo para simplificar su identificaci\u00f3n.<\/li><li>En <strong>descripci\u00f3n<\/strong> elegimos el tipo de sensor que estamos utilizando.<\/li><\/ul><p>Al terminar selecciona <b>siguiente<\/b>.<\/p><h2>Asignar dispositivo<\/h2><p>En la ventana de <strong>asignaci\u00f3n de canales<\/strong>, podemos seleccionar un punto de an\u00e1lisis en una m\u00e1quina donde agregar nuestro dispositivo phantom, podemos agregar un punto diferente para cada canal.<\/p><h2>Configura alarmas y pinzas\u00a0<\/h2><p>En la siguiente ventana, podemos configurar el tipo de pinza (clamp) que conectaremos en cada canal, tenemos disponibles pinzas de 50, 100, 250 y 500 Amp.<\/p><p>Tambi\u00e9n, podemos establecer un umbral preestablecido\u00a0 de amperaje para cada canal y la temperatura interna. Si se supera el valor de la alarma, el sensor se despertar\u00e1 inmediatamente y har\u00e1 una medici\u00f3n no programada.<\/p><div class=\"page\" title=\"Page 28\"><div class=\"layoutArea\"><div class=\"column\"><h2>Completando la configuraci\u00f3n<\/h2><\/div><\/div><\/div><div class=\"page\" title=\"Page 29\"><div class=\"layoutArea\"><div class=\"column\">Finalmente, el asistente nos la opci\u00f3n de agregar otro dispositivo phantom a nuestra base de datos, tambi\u00e9n con el bot\u00f3n anterior podemos regresar y realizar correcciones la phantom reci\u00e9n agregado. Si no hay m\u00e1s cambios selecciona <strong>terminar<\/strong>. Pueden cancelarse los cambios y configuraciones <strong>cerrando<\/strong> el asistente o seleccionado <strong>cancelar<\/strong>.<\/div><div>\u00a0<\/div><p>Para saber m\u00e1s sobre nuestro sistema Phantom visita la secci\u00f3n de <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/www.erbessd-instruments.com\/es\/monitoreo-continuo\/\">Sistema de Monitoreo de Vibraciones.\u00a0<\/a><\/span><\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"parent":18449,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","doc_tag":[],"class_list":["post-18596","docs","type-docs","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Docs for Sensores Phantom &#8211; Phantom de Corriente &#8211; ERBESSD INSTRUMENTS<\/title>\n<meta name=\"description\" content=\"El sensor Phantom de corriente permite un registro del amperaje de las l\u00edneas el\u00e9ctricas a monitorear. Monitoree hasta 3 l\u00edneas diferentes por cada sensor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Phantom de Corriente\" \/>\n<meta property=\"og:description\" content=\"El sensor Phantom de corriente permite un registro del amperaje de las l\u00edneas el\u00e9ctricas a monitorear. Monitoree hasta 3 l\u00edneas diferentes por cada sensor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/\" \/>\n<meta property=\"og:site_name\" content=\"ERBESSD INSTRUMENTS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erbessdinstrumentsco\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-22T22:24:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ErbessdRel\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Docs for Sensores Phantom &#8211; Phantom de Corriente &#8211; ERBESSD INSTRUMENTS","description":"El sensor Phantom de corriente permite un registro del amperaje de las l\u00edneas el\u00e9ctricas a monitorear. Monitoree hasta 3 l\u00edneas diferentes por cada sensor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/","og_locale":"es_ES","og_type":"article","og_title":"Phantom de Corriente","og_description":"El sensor Phantom de corriente permite un registro del amperaje de las l\u00edneas el\u00e9ctricas a monitorear. Monitoree hasta 3 l\u00edneas diferentes por cada sensor.","og_url":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/","og_site_name":"ERBESSD INSTRUMENTS","article_publisher":"https:\/\/www.facebook.com\/erbessdinstrumentsco","article_modified_time":"2021-07-22T22:24:20+00:00","twitter_card":"summary_large_image","twitter_site":"@ErbessdRel","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/","url":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/","name":"Docs for Sensores Phantom &#8211; Phantom de Corriente &#8211; ERBESSD INSTRUMENTS","isPartOf":{"@id":"https:\/\/www.erbessd-instruments.com\/#website"},"datePublished":"2019-10-14T19:05:35+00:00","dateModified":"2021-07-22T22:24:20+00:00","description":"El sensor Phantom de corriente permite un registro del amperaje de las l\u00edneas el\u00e9ctricas a monitorear. Monitoree hasta 3 l\u00edneas diferentes por cada sensor.","breadcrumb":{"@id":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-corriente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erbessd-instruments.com\/es\/"},{"@type":"ListItem","position":2,"name":"Phantom","item":"https:\/\/www.erbessd-instruments.com\/docs\/phantom\/"},{"@type":"ListItem","position":3,"name":"Sensores Phantom","item":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/"},{"@type":"ListItem","position":4,"name":"Phantom de Corriente"}]},{"@type":"WebSite","@id":"https:\/\/www.erbessd-instruments.com\/#website","url":"https:\/\/www.erbessd-instruments.com\/","name":"ERBESSD INSTRUMENTS","description":"Vibration Analyzer, Online Monitoring, Video Deflection, &amp; Balancing Machine Manufacturer","publisher":{"@id":"https:\/\/www.erbessd-instruments.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erbessd-instruments.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.erbessd-instruments.com\/#organization","name":"ERBESSD INSTRUMENTS","url":"https:\/\/www.erbessd-instruments.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.erbessd-instruments.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.erbessd-instruments.com\/wp-content\/uploads\/2021\/06\/erbessd_instruments_logo.png","contentUrl":"https:\/\/www.erbessd-instruments.com\/wp-content\/uploads\/2021\/06\/erbessd_instruments_logo.png","width":1073,"height":138,"caption":"ERBESSD INSTRUMENTS"},"image":{"@id":"https:\/\/www.erbessd-instruments.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erbessdinstrumentsco","https:\/\/x.com\/ErbessdRel","https:\/\/www.linkedin.com\/company\/erbessdinstrumentsco","https:\/\/www.pinterest.com\/4d2ab37d590061eda78ee907c11410\/","https:\/\/www.youtube.com\/channel\/UCMi2XxcHeufIw5WVkcPg98A"]}]}},"comment_count":0,"_links":{"self":[{"href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/docs\/18596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/types\/docs"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/comments?post=18596"}],"version-history":[{"count":5,"href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/docs\/18596\/revisions"}],"predecessor-version":[{"id":10117336,"href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/docs\/18596\/revisions\/10117336"}],"up":[{"embeddable":true,"href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/docs\/18449"}],"next":[{"title":"Phantom de RPM","link":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/rpm-phantom\/","href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/docs\/18724"}],"prev":[{"title":"Phantom de Temperatura","link":"https:\/\/www.erbessd-instruments.com\/es\/docs\/phantom\/sensores-phantom\/phantom-de-temperatura\/","href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/docs\/18511"}],"wp:attachment":[{"href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/media?parent=18596"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.erbessd-instruments.com\/es\/wp-json\/wp\/v2\/doc_tag?post=18596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}